{"id":302,"count":3,"description":"","link":"https:\/\/lesescoles.com\/es\/tag\/nadal\/","name":"Nadal","slug":"nadal","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/lesescoles.com\/es\/wp-json\/wp\/v2\/tags\/302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lesescoles.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/lesescoles.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/lesescoles.com\/es\/wp-json\/wp\/v2\/posts?tags=302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}